{"id":7490,"date":"2023-06-23T12:32:07","date_gmt":"2023-06-23T12:32:07","guid":{"rendered":"https:\/\/pagani-design.eu\/?page_id=7490"},"modified":"2024-09-20T12:20:47","modified_gmt":"2024-09-20T12:20:47","slug":"informacion-legal","status":"publish","type":"page","link":"https:\/\/pagani-design.eu\/es\/informacion-legal\/","title":{"rendered":"Menciones legales"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"7490\" class=\"elementor elementor-7490\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21c507e elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"21c507e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e10d87b\" data-id=\"e10d87b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2a4804 elementor-widget elementor-widget-text-editor\" data-id=\"e2a4804\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Definiciones<\/h2><p><b>Cliente :<\/b> todo profesional o persona f\u00edsica capaz en el sentido de los art\u00edculos 1123 y siguientes del C\u00f3digo civil, o persona moral, que visite el Sitio objeto de las presentes condiciones generales.<br \/><b>Prestaciones y Servicios :<\/b> <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> pone a disposici\u00f3n de los clientes :<\/p><p><b>Contenu :<\/b> Conjunto de elementos que componen la informaci\u00f3n presentada en el Sitio, en particular textos - im\u00e1genes - v\u00eddeos.<\/p><p><b>Informaci\u00f3n clientes :<\/b> Ci apr\u00e8s d\u00e9nomm\u00e9 \u00ab Information (s) \u00bb qui correspondent \u00e0 l'ensemble des donn\u00e9es personnelles susceptibles d'\u00eatre d\u00e9tenues par <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> para la gesti\u00f3n de su cuenta, la gesti\u00f3n de la relaci\u00f3n con el cliente y para fines de an\u00e1lisis y estad\u00edsticos.<\/p><p><b>Utilisateur :<\/b> Los internautas se conectan utilizando el sitio web mencionado.<\/p><p><b>Informaci\u00f3n personal :<\/b> \u00ab Las informaciones que permitan, bajo cualquier forma que sea, directamente o no, la identificaci\u00f3n de las personas f\u00edsicas a las que se aplican\u00bb (art\u00edculo 4 de la ley n\u00b0 78-17 de 6 de enero de 1978).<\/p><p>Los t\u00e9rminos \u00abdonn\u00e9es \u00e0 caract\u00e8re personnel\u00bb, \u00abpersonne concern\u00e9e\u00bb, \u00absous traitant\u00bb et \u00abdonn\u00e9es sensibles\u00bb ont le sens d\u00e9fini par le R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679)<\/p><h2>1. Presentaci\u00f3n del sitio web.<\/h2><p>De conformidad con el art\u00edculo 6 de la Ley n\u00ba 2004-575 de 21 de junio de 2004 sobre la confianza en la econom\u00eda digital, se informa a los usuarios del sitio web de que <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> l'identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi:<\/p><p>ALAMBIK\u00a0<br \/>Conmutador O2 - 222-224 Boulevard Gustave Flaubert 63000 Clermont-Ferrand 09 3 645 729\u00a0<br \/><span style=\"color: var(--minimog-color-text);\">bonjour@pagani-design.eu<\/span><\/p><h2>2. Condiciones generales de utilizaci\u00f3n del sitio y de los servicios propuestos.<\/h2><p>El Sitio constituye una obra de arte protegida por las disposiciones del C\u00f3digo de la Propiedad Intelectual y las Normas Internacionales aplicables. El Cliente no podr\u00e1 en ning\u00fan caso reutilizar, copiar o explotar para su propio beneficio la totalidad o parte de los elementos o trabajos del Sitio.<\/p><p>Utilizaci\u00f3n del sitio web <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> implica la aceptaci\u00f3n plena y completa de las condiciones generales de uso descritas anteriormente. Estas condiciones de uso podr\u00e1n ser modificadas o completadas en cualquier momento por los usuarios del sitio. <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> por lo que se les invita a consultarlos de forma regular.<\/p><p>Ce site internet est normalement accessible \u00e0 tout moment aux utilisateurs. Une interruption pour raison de maintenance technique peut \u00eatre toutefois d\u00e9cid\u00e9e par <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a>, que tambi\u00e9n se esforzar\u00e1 por comunicar a los usuarios con antelaci\u00f3n las fechas y horas de la intervenci\u00f3n. Sitio web <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> es actualizado peri\u00f3dicamente por <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> responsable. Del mismo modo, las menciones legales pueden modificarse en cualquier momento: no obstante, se imponen al usuario, al que se invita a dirigirse con la mayor frecuencia posible para tener conocimiento de las mismas.<\/p><h2>3. Description des services fournis.<\/h2><p>El sitio web <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> a pour objet de fournir une information concernant l'ensemble des activit\u00e9s de la soci\u00e9t\u00e9. <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> se esfuerza por ofrecer en el sitio web <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> des informations aussi pr\u00e9cises que possible. Sin embargo, no podr\u00e1 ser considerado responsable de los errores, inexactitudes o carencias en la puesta en pr\u00e1ctica, ya sean de su responsabilidad o de la de los terceros que le proporcionen dicha informaci\u00f3n.<\/p><p>Toda la informaci\u00f3n sobre el sitio web <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> son indicativos y pueden variar. Por otra parte, la informaci\u00f3n que figura en el sitio web <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> no son exhaustivos. Se facilitan a reserva de las modificaciones que se hayan introducido despu\u00e9s de su puesta en l\u00ednea.<\/p><h2>4. Limitaciones contractuales de los datos t\u00e9cnicos.<\/h2><p>El sitio utiliza la tecnolog\u00eda JavaScript. El sitio Internet no se hace responsable de los da\u00f1os materiales relacionados con el uso del sitio. Adem\u00e1s, el usuario del sitio se compromete a acceder al sitio utilizando un material reciente, que no contenga virus y con un navegador de \u00faltima generaci\u00f3n actualizado. <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> se lleva a cabo en un prestador en el territorio de la Uni\u00f3n Europea de conformidad con las disposiciones del Reglamento General de Protecci\u00f3n de Datos (RGPD: n\u00b0 2016-679).<\/p><p>El objetivo es ofrecer un servicio que garantice el mejor nivel de accesibilidad. El conserje garantiza la continuidad de su servicio 24 horas al d\u00eda, todos los d\u00edas del a\u00f1o. No obstante, se reserva la posibilidad de interrumpir el servicio de alojamiento durante los periodos m\u00e1s breves posibles, en particular con fines de mantenimiento, mejora de sus infraestructuras, aver\u00eda de las mismas o si las Prestaciones y Servicios generan un tr\u00e1fico considerado anormal.<\/p><p><a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> y el proveedor no podr\u00e1n ser considerados responsables en caso de aver\u00eda de la red Internet, de las l\u00edneas telef\u00f3nicas o del material inform\u00e1tico y telef\u00f3nico, en particular, en caso de aver\u00eda de la red que impida el acceso al servidor.<\/p><h2>5. Limitations de responsabilit\u00e9.<\/h2><p><a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> agit en tant qu'\u00e9diteur du site. <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> es responsable de la calidad y veracidad del Contenido que publica.<\/p><p><a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> no podr\u00e1 ser considerado responsable de los da\u00f1os directos o indirectos causados al material del usuario durante el acceso al sitio Internet <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a>, y como resultado de la utilizaci\u00f3n de un material que no responde a las especificaciones indicadas en el punto 4 o de la aparici\u00f3n de un error o incompatibilidad.<\/p><p><a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> tampoco podr\u00e1 ser considerado responsable de los da\u00f1os indirectos (por ejemplo, p\u00e9rdida de mercado o p\u00e9rdida de una oportunidad) derivados de la utilizaci\u00f3n del sitio. <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a>. Los usuarios tienen a su disposici\u00f3n espacios interactivos (posibilidad de plantear preguntas en el espacio de contacto). <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> se reserva el derecho de suprimir, sin demora, todo contenido depositado en este espacio que se ajuste a la legislaci\u00f3n aplicable en Francia, en particular a las disposiciones relativas a la protecci\u00f3n de datos. Este es el caso, <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> se reserva asimismo la posibilidad de exigir la responsabilidad civil y\/o penal del usuario, en particular en caso de mensaje de contenido racista, injurioso, difamatorio o pornogr\u00e1fico, sea cual sea el soporte utilizado (texto, fotograf\u00eda...).<\/p><h2>6. 6. Gesti\u00f3n de datos personales.<\/h2><p>El Cliente est\u00e1 informado de las normativas relativas a la comunicaci\u00f3n de marketing, la ley del 21 de junio de 2014 para la confianza en la Econom\u00eda Num\u00e9rica, la Ley Inform\u00e1tica y Libertad del 06 de agosto de 2004 as\u00ed como del Reglamento General de Protecci\u00f3n de Datos (RGPD : n\u00b0 2016-679).<\/p><h3>6.1 Responsables de la recogida de datos personales<\/h3><p>Para los Datos Personales recogidos en el marco de la creaci\u00f3n de la cuenta personal del Usuario y de su navegaci\u00f3n en el Sitio, el responsable del tratamiento de los Datos Personales es: ALAMBIK. <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a>est\u00e1 representado por ALAMBIK, su representante legal<\/p><p>Como responsable del tratamiento de los datos que recopila, <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> se compromete a respetar las disposiciones legales vigentes. Corresponde al Cliente, en particular, establecer las finalidades de sus tratamientos de datos, proporcionar a sus prospectos y clientes, a partir de la recogida de sus consentimientos, una informaci\u00f3n completa sobre el tratamiento de sus datos personales y mantener un registro de los tratamientos conforme a la realidad. Cada vez que <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> traite des Donn\u00e9es Personnelles, <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> adopta todas las medidas razonables para garantizar la exactitud y pertinencia de los datos personales con respecto a los fines para los que se utilizan <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> les traite.<\/p><h3>6.2 Finalidad de los datos recogidos<\/h3><p><a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> puede tratar todos o parte de los datos:<\/p><ul><li>para permitir la navegaci\u00f3n por el Sitio y la gesti\u00f3n y el seguimiento de las prestaciones y servicios solicitados por el usuario: datos de conexi\u00f3n y uso del Sitio, facturaci\u00f3n, historial de solicitudes, etc.<\/li><li>para prevenir y combatir el fraude inform\u00e1tico (spamming, hacking...): material inform\u00e1tico utilizado para la navegaci\u00f3n, direcci\u00f3n IP, contrase\u00f1a (hash)<\/li><li>para mejorar la navegaci\u00f3n en el Sitio: datos de conexi\u00f3n y de uso<\/li><li>para realizar encuestas de satisfacci\u00f3n facultativas sobre <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> Direcci\u00f3n de correo electr\u00f3nico<\/li><li>para enviar mensajes de comunicaci\u00f3n (SMS, correo electr\u00f3nico): n\u00famero de tel\u00e9fono, direcci\u00f3n de correo electr\u00f3nico<\/li><\/ul><p><a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> no comercialice sus datos personales, que s\u00f3lo se utilizar\u00e1n para fines estad\u00edsticos o de an\u00e1lisis.<\/p><h3>6.3 Derecho de acceso, rectificaci\u00f3n y oposici\u00f3n<\/h3><p>Conform\u00e9ment \u00e0 la r\u00e9glementation europ\u00e9enne en vigueur, les Utilisateurs de <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> disponen de los siguientes derechos :<\/p><ul><li>derecho de acceso (art\u00edculo 15 del RGPD) y de rectificaci\u00f3n (art\u00edculo 16 del RGPD), de puesta al d\u00eda, de complemento de los datos de los Usuarios derecho de bloqueo o de supresi\u00f3n de los datos de car\u00e1cter personal de los Usuarios (art\u00edculo 17 del RGPD), lorsqu'elles sont inexactes, incompl\u00e8tes, \u00e9quivoques, p\u00e9rim\u00e9es, ou dont la collecte, l'utilisation, la communication ou la conservation est interdite<\/li><li>derecho a retirar en cualquier momento un consentimiento (art\u00edculo 13-2c RGPD)<\/li><li>Derecho a la limitaci\u00f3n del tratamiento de los datos de los usuarios (art\u00edculo 18 del RGPD)<\/li><li>derecho de oposici\u00f3n al tratamiento de los datos de los usuarios (art\u00edculo 21 del RGPD)<\/li><li>derecho a la portabilidad de los datos facilitados por los usuarios, siempre que dichos datos sean objeto de tratamientos automatizados basados en su consentimiento o en un contrato (art\u00edculo 20 del RGPD).<\/li><li>derecho a definir el tipo de datos de los Usuarios tras su fallecimiento y a elegir a qui\u00e9n <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> deber\u00e1 comunicar (o no) sus datos a un tercero que haya designado previamente<\/li><\/ul><p>D\u00e8s que <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> a connaissance du d\u00e9c\u00e8s d'un Utilisateur et \u00e0 d\u00e9faut d'instructions de sa part, <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> se comprometa a destruir sus datos, salvo si su conservaci\u00f3n es necesaria a efectos probatorios o para responder a una obligaci\u00f3n legal.<\/p><p>Si el usuario desea saber c\u00f3mo <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> utiliza sus Datos Personales, solicita que se rectifiquen o se opone a su tratamiento, el Usuario puede ponerse en contacto con <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> par \u00e9crit \u00e0 l'adresse suivante :<\/p><p>ALAMBIK Francia <br \/>222-224 Boulevard Gustave Flaubert 63000- Ferrand.<\/p><p>En este caso, el usuario deber\u00e1 indicar los datos personales que desea que se le comuniquen. <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> corrige, actualiza o suprime, identific\u00e1ndose previamente con una copia de un documento de identidad (carn\u00e9 de identidad o pasaporte).<\/p><p>Las solicitudes de supresi\u00f3n de datos personales estar\u00e1n sujetas a las obligaciones impuestas a <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> par la loi, notamment en mati\u00e8re de conservation ou d'archivage des documents. Enfin, les Utilisateurs de <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> pueden presentar una denuncia ante las autoridades de control, en particular la CNIL (https:\/\/www.cnil.fr\/fr\/plaintes).<\/p><h3>6.4 No comunicaci\u00f3n de datos personales<\/h3><p><a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> se proh\u00edbe tratar, almacenar o transferir la informaci\u00f3n recopilada sobre sus clientes a un pa\u00eds situado fuera de la Uni\u00f3n Europea o reconocido como \u00abno adecuado\u00bb por la Comisi\u00f3n Europea sin informar previamente al cliente. Pour autant, <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> queda libre de elegir a sus sustitutos t\u00e9cnicos y comerciales a condici\u00f3n de que presenten las garant\u00edas suficientes con arreglo a las exigencias del Reglamento General de Protecci\u00f3n de Datos (RGPD: n\u00b0 2016-679).<\/p><p><a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> se compromete a tomar todas las precauciones necesarias para preservar la seguridad de la Informaci\u00f3n y, en particular, a no comunicarla a personas no autorizadas. No obstante, si un incidente que afecte a la integridad o confidencialidad de la Informaci\u00f3n del Cliente es conocido por <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a>, Deber\u00e1 informar al Cliente en los plazos m\u00e1s breves y comunicarle las medidas correctivas adoptadas. Adem\u00e1s <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> ne collect aucune \u00ab donn\u00e9es sensibles \u00bb.<\/p><p>Los datos personales del usuario pueden ser tratados por filiales de <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> et des sous-traitants (prestataires de services), exclusivement afin de r\u00e9aliser les finalit\u00e9s de la pr\u00e9sente politique.<\/p><p>Dentro del l\u00edmite de sus respectivas atribuciones y para los fines expuestos a continuaci\u00f3n, las principales personas susceptibles de tener acceso a los datos de los Usuarios de <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> son principalmente los agentes de nuestro servicio al cliente.<\/p><div>\u00a0<\/div><h2>7. Notificaci\u00f3n de incidente<\/h2><p>Sean cuales sean los esfuerzos realizados, ning\u00fan m\u00e9todo de transmisi\u00f3n por Internet ni ning\u00fan m\u00e9todo de almacenamiento electr\u00f3nico es completamente seguro. En consecuencia, no podemos garantizar una seguridad absoluta. Si tenemos conocimiento de un fallo de seguridad, advertiremos a los usuarios afectados para que tomen las medidas oportunas. Nuestros procedimientos de notificaci\u00f3n de incidentes tienen en cuenta nuestras obligaciones legales, tanto nacionales como europeas. Nos comprometemos a informar plenamente a nuestros clientes de todas las cuestiones relevantes para la seguridad de su cuenta y a facilitarles toda la informaci\u00f3n necesaria para ayudarles a respetar sus propias obligaciones reglamentarias en materia de notificaci\u00f3n.<\/p><p>Ninguna informaci\u00f3n personal del usuario del sitio web <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> no se publique a petici\u00f3n del usuario, se cambie, se transfiera, se ceda o se venda en un soporte de terceros. Seule l'hypoth\u00e8se du rachat de <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> y de sus derechos permita la transmisi\u00f3n de dicha informaci\u00f3n al eventual adquirente que estar\u00e1 sujeto a su vez a la misma obligaci\u00f3n de conservaci\u00f3n y modificaci\u00f3n de los datos frente al usuario del sitio web <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a>.<\/p><h3>Seguridad<\/h3><p>Para garantizar la seguridad y confidencialidad de los datos personales y sanitarios, <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> utiliza redes protegidas por dispositivos est\u00e1ndar, como el pare-feu, la seudonimizaci\u00f3n, el cifrado y la contrase\u00f1a.<\/p><p>Durante el tratamiento de datos personales, <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a>adopte todas las medidas razonables para protegerlos de cualquier p\u00e9rdida, uso indebido, acceso no autorizado, divulgaci\u00f3n, alteraci\u00f3n o destrucci\u00f3n.<\/p><h2>9. Liens hypertextes \u00ab cookies \u00bb et balises (\u201ctags\u201d) internet<\/h2><p>El sitio <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> contiene un cierto n\u00famero de enlaces hipertextuales a otros sitios, establecidos con la autorizaci\u00f3n de <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a>. Cependant, <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> no tiene la posibilidad de verificar el contenido de los sitios visitados y, por lo tanto, no asume ninguna responsabilidad al respecto.<\/p><p>Aunque decida desactivar las cookies, acepta que el sitio web pueda utilizarlas. Puede desactivar estas cookies en cualquier momento y de forma gratuita a partir de las posibilidades de desactivaci\u00f3n que se le ofrecen y detallan a continuaci\u00f3n, aunque esto puede reducir o impedir el acceso a todos o parte de los Servicios propuestos por el sitio.<\/p><h3>9.1. \u00abCOOKIES\u00bb<\/h3><p>Una \u00abcookie\u00bb es un peque\u00f1o archivo de informaci\u00f3n enviado al navegador del Usuario y registrado en el terminal del Usuario (por ejemplo: ordenador, smartphone), (en adelante \u00abCookies\u00bb). Este archivo contiene informaci\u00f3n como el nombre de dominio del Usuario, el proveedor de acceso a Internet del Usuario, el sistema de explotaci\u00f3n del Usuario, as\u00ed como la fecha y hora de acceso. En ning\u00fan caso las Cookies pueden da\u00f1ar el terminal del Usuario.<\/p><p><a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> es susceptible de traiter les informations de l'Utilisateur concernant sa visite du Site, telles que les pages consult\u00e9es, les recherches effectu\u00e9es. Estos datos permiten <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> mejorar el contenido del Sitio y la navegaci\u00f3n del Usuario.<\/p><p>Para facilitar la navegaci\u00f3n y\/o la prestaci\u00f3n de los servicios propuestos por el Sitio, el Usuario puede configurar su navegador de manera que le permita decidir si desea o no aceptar las Cookies registradas en su terminal o, por el contrario, rechazarlas, ya sea de forma sistem\u00e1tica, ya sea en funci\u00f3n de su emisor. El Usuario tambi\u00e9n puede configurar su navegador para que le proponga aceptar o rechazar las Cookies antes de que una Cookie se registre en su terminal. <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> informa al Usuario de que, en este caso, es posible que las funcionalidades de su sistema de navegaci\u00f3n no est\u00e9n disponibles en su totalidad.<\/p><p>Si el Usuario rechaza el registro de Cookies en su terminal o en su navegador, o si suprime las que se registren, el Usuario ser\u00e1 informado de que su navegaci\u00f3n y su experiencia en el Sitio pueden verse limitadas. Esto tambi\u00e9n podr\u00eda ocurrir si <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> o uno de sus proveedores no puede reconocer, a efectos de compatibilidad t\u00e9cnica, el tipo de navegador utilizado por el terminal, los par\u00e1metros de idioma y de imagen o el pa\u00eds desde el que el terminal parece estar conectado a Internet.<\/p><p>Este es el caso, <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> declina toda responsabilidad por las consecuencias relacionadas con el funcionamiento defectuoso del Sitio y de los servicios eventualmente propuestos por <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a>, como consecuencia (i) del rechazo de Cookies por parte del Usuario (ii) de la imposibilidad para <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> de registrar o consultar las Cookies necesarias para su funcionamiento en funci\u00f3n de la elecci\u00f3n del Usuario. La configuraci\u00f3n de cada navegador es diferente para gestionar las cookies y las opciones del navegador. Est\u00e1 descrita en el men\u00fa de ayuda del navegador, que permite saber de qu\u00e9 manera el Usuario puede modificar sus deseos en materia de Cookies.<\/p><p>En todo momento, el Usuario podr\u00e1 optar por expresar y modificar sus deseos en materia de Cookies. <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> podr\u00e1, adem\u00e1s, recurrir a los servicios de prestatarios externos para que le ayuden a recabar y tratar la informaci\u00f3n descrita en esta secci\u00f3n.<\/p><p>Adem\u00e1s, haciendo clic en los iconos de las redes sociales Twitter, Facebook, Linkedin y Google Plus que aparecen en la p\u00e1gina de <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> ou dans son application mobile et si l'Utilisateur a accept\u00e9 le d\u00e9p\u00f4t de cookies en poursuivant sa navigation sur le Site Internet ou l'application mobile de <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a>, Twitter, Facebook, Linkedin y Google Plus tambi\u00e9n pueden enviar cookies a su ordenador, tableta o tel\u00e9fono m\u00f3vil.<\/p><p>Estos tipos de cookies no se depositan en sus terminales a condici\u00f3n de que usted lo consienta, al continuar su navegaci\u00f3n por el Sitio Internet o la aplicaci\u00f3n m\u00f3vil de <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a>. \u00c0 tout moment, l'Utilisateur peut n\u00e9anmoins revenir sur son consentement \u00e0 ce que <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> d\u00e9pose ce type de cookies.<\/p><h3>Art\u00edculo 9.2. BALIZAS (\u201cTAGS\u201d) INTERNET<\/h3><p><a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> puede emplear ocasionalmente balizas de Internet (tambi\u00e9n denominadas \u00abetiquetas\u00bb, o balizas de acci\u00f3n, GIF a un p\u00edxel, GIF transparentes, GIF invisibles y GIF uno a uno) y desplegarlas a trav\u00e9s de un socio especializado en an\u00e1lisis web que pueda encontrarlas (y por tanto almacenar la informaci\u00f3n correspondiente, incluida la direcci\u00f3n IP del Usuario) en un pa\u00eds extranjero.<\/p><p>Estas balizas se colocan a la vez en los anuncios en l\u00ednea que permiten a los internautas acceder al Sitio, y en las distintas p\u00e1ginas del mismo.<\/p><p>Esta tecnolog\u00eda permite <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> evaluar las respuestas de los visitantes al Sitio y la eficacia de sus acciones (por ejemplo, el n\u00famero de veces que se abre una p\u00e1gina y la informaci\u00f3n consultada), as\u00ed como la utilizaci\u00f3n de este Sitio por parte del Usuario.<\/p><p>El prestador externo podr\u00e1, en su caso, recopilar informaci\u00f3n sobre los visitantes del Sitio y de otros sitios de Internet gracias a estas balizas, elaborar informes sobre la actividad del Sitio a la atenci\u00f3n de <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a>, y prestar otros servicios relacionados con su uso y el de Internet.<\/p><h2>10. Derecho aplicable y atribuci\u00f3n de jurisdicci\u00f3n.<\/h2><p>Todos los litigios relacionados con el uso del sitio web <a href=\"https:\/\/pagani-design.eu\/es\/\">https:\/\/pagani-design.eu\/<\/a> est\u00e1 sujeta al derecho franc\u00e9s. En los casos en que la ley no lo permita, se atribuir\u00e1 jurisdicci\u00f3n exclusiva a los tribunales competentes de los Estados miembros.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9finitions Client : tout professionnel ou personne physique capable au sens des articles 1123 et suivants du Code civil, ou personne morale, qui visite le Site objet des pr\u00e9sentes conditions g\u00e9n\u00e9rales.Prestations et Services : https:\/\/pagani-design.eu\/ met \u00e0 disposition des Clients : Contenu : Ensemble des \u00e9l\u00e9ments constituants l\u2019information pr\u00e9sente sur le Site, notamment textes \u2013 images \u2013 vid\u00e9os. Informations clients : Ci apr\u00e8s d\u00e9nomm\u00e9 \u00ab Information (s) \u00bb qui correspondent \u00e0 l\u2019ensemble des donn\u00e9es personnelles susceptibles d\u2019\u00eatre d\u00e9tenues par https:\/\/pagani-design.eu\/ pour la gestion de votre compte, de la gestion de la relation client et \u00e0 des fins d\u2019analyses et de statistiques. Utilisateur : Internaute se connectant, utilisant le site susnomm\u00e9. Informations personnelles : \u00ab Les informations qui permettent, sous quelque forme que ce soit, directement ou non, l&#8217;identification des personnes physiques auxquelles elles s&#8217;appliquent \u00bb (article 4 de la loi n\u00b0 78-17 du 6 janvier 1978). Les termes \u00ab donn\u00e9es \u00e0 caract\u00e8re personnel \u00bb, \u00ab personne concern\u00e9e \u00bb, \u00ab sous traitant \u00bb et \u00ab donn\u00e9es sensibles \u00bb ont le sens d\u00e9fini par le R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679) 1. Pr\u00e9sentation du site internet. En vertu de l&#8217;article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l&#8217;\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet https:\/\/pagani-design.eu\/ l&#8217;identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi: ALAMBIK\u00a0O2 switch \u2013 222-224 Boulevard Gustave Flaubert 63000 Clermont-Ferrand 09 3 645 729\u00a0bonjour@pagani-design.eu 2. Conditions g\u00e9n\u00e9rales d\u2019utilisation du site et des services propos\u00e9s. Le Site constitue une \u0153uvre de l\u2019esprit prot\u00e9g\u00e9e par les dispositions du Code de la Propri\u00e9t\u00e9 Intellectuelle et des R\u00e9glementations Internationales applicables. Le Client ne peut en aucune mani\u00e8re r\u00e9utiliser, c\u00e9der ou exploiter pour son propre compte tout ou partie des \u00e9l\u00e9ments ou travaux du Site. L\u2019utilisation du site https:\/\/pagani-design.eu\/ implique l\u2019acceptation pleine et enti\u00e8re des conditions g\u00e9n\u00e9rales d\u2019utilisation ci-apr\u00e8s d\u00e9crites. Ces conditions d\u2019utilisation sont susceptibles d\u2019\u00eatre modifi\u00e9es ou compl\u00e9t\u00e9es \u00e0 tout moment, les utilisateurs du site https:\/\/pagani-design.eu\/ sont donc invit\u00e9s \u00e0 les consulter de mani\u00e8re r\u00e9guli\u00e8re. Ce site internet est normalement accessible \u00e0 tout moment aux utilisateurs. Une interruption pour raison de maintenance technique peut \u00eatre toutefois d\u00e9cid\u00e9e par https:\/\/pagani-design.eu\/, qui s\u2019efforcera alors de communiquer pr\u00e9alablement aux utilisateurs les dates et heures de l\u2019intervention. Le site web https:\/\/pagani-design.eu\/ est mis \u00e0 jour r\u00e9guli\u00e8rement par https:\/\/pagani-design.eu\/ responsable. De la m\u00eame fa\u00e7on, les mentions l\u00e9gales peuvent \u00eatre modifi\u00e9es \u00e0 tout moment : elles s\u2019imposent n\u00e9anmoins \u00e0 l\u2019utilisateur qui est invit\u00e9 \u00e0 s\u2019y r\u00e9f\u00e9rer le plus souvent possible afin d\u2019en prendre connaissance. 3. Description des services fournis. Le site internet https:\/\/pagani-design.eu\/ a pour objet de fournir une information concernant l\u2019ensemble des activit\u00e9s de la soci\u00e9t\u00e9. https:\/\/pagani-design.eu\/ s\u2019efforce de fournir sur le site https:\/\/pagani-design.eu\/ des informations aussi pr\u00e9cises que possible. Toutefois, il ne pourra \u00eatre tenu responsable des oublis, des inexactitudes et des carences dans la mise \u00e0 jour, qu\u2019elles soient de son fait ou du fait des tiers partenaires qui lui fournissent ces informations. Toutes les informations indiqu\u00e9es sur le site https:\/\/pagani-design.eu\/ sont donn\u00e9es \u00e0 titre indicatif, et sont susceptibles d\u2019\u00e9voluer. Par ailleurs, les renseignements figurant sur le site https:\/\/pagani-design.eu\/ ne sont pas exhaustifs. Ils sont donn\u00e9s sous r\u00e9serve de modifications ayant \u00e9t\u00e9 apport\u00e9es depuis leur mise en ligne. 4. Limitations contractuelles sur les donn\u00e9es techniques. Le site utilise la technologie JavaScript. Le site Internet ne pourra \u00eatre tenu responsable de dommages mat\u00e9riels li\u00e9s \u00e0 l\u2019utilisation du site. De plus, l\u2019utilisateur du site s\u2019engage \u00e0 acc\u00e9der au site en utilisant un mat\u00e9riel r\u00e9cent, ne contenant pas de virus et avec un navigateur de derni\u00e8re g\u00e9n\u00e9ration mis-\u00e0-jour Le site https:\/\/pagani-design.eu\/ est h\u00e9berg\u00e9 chez un prestataire sur le territoire de l\u2019Union Europ\u00e9enne conform\u00e9ment aux dispositions du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679) L\u2019objectif est d\u2019apporter une prestation qui assure le meilleur taux d\u2019accessibilit\u00e9. L\u2019h\u00e9bergeur assure la continuit\u00e9 de son service 24 Heures sur 24, tous les jours de l\u2019ann\u00e9e. Il se r\u00e9serve n\u00e9anmoins la possibilit\u00e9 d\u2019interrompre le service d\u2019h\u00e9bergement pour les dur\u00e9es les plus courtes possibles notamment \u00e0 des fins de maintenance, d\u2019am\u00e9lioration de ses infrastructures, de d\u00e9faillance de ses infrastructures ou si les Prestations et Services g\u00e9n\u00e8rent un trafic r\u00e9put\u00e9 anormal. https:\/\/pagani-design.eu\/ et l\u2019h\u00e9bergeur ne pourront \u00eatre tenus responsables en cas de dysfonctionnement du r\u00e9seau Internet, des lignes t\u00e9l\u00e9phoniques ou du mat\u00e9riel informatique et de t\u00e9l\u00e9phonie li\u00e9 notamment \u00e0 l\u2019encombrement du r\u00e9seau emp\u00eachant l\u2019acc\u00e8s au serveur. 5. Limitations de responsabilit\u00e9. https:\/\/pagani-design.eu\/ agit en tant qu\u2019\u00e9diteur du site. https:\/\/pagani-design.eu\/ est responsable de la qualit\u00e9 et de la v\u00e9racit\u00e9 du Contenu qu\u2019il publie. https:\/\/pagani-design.eu\/ ne pourra \u00eatre tenu responsable des dommages directs et indirects caus\u00e9s au mat\u00e9riel de l\u2019utilisateur, lors de l\u2019acc\u00e8s au site internet https:\/\/pagani-design.eu\/, et r\u00e9sultant soit de l\u2019utilisation d\u2019un mat\u00e9riel ne r\u00e9pondant pas aux sp\u00e9cifications indiqu\u00e9es au point 4, soit de l\u2019apparition d\u2019un bug ou d\u2019une incompatibilit\u00e9. https:\/\/pagani-design.eu\/ ne pourra \u00e9galement \u00eatre tenu responsable des dommages indirects (tels par exemple qu\u2019une perte de march\u00e9 ou perte d\u2019une chance) cons\u00e9cutifs \u00e0 l\u2019utilisation du site https:\/\/pagani-design.eu\/. Des espaces interactifs (possibilit\u00e9 de poser des questions dans l\u2019espace contact) sont \u00e0 la disposition des utilisateurs. https:\/\/pagani-design.eu\/ se r\u00e9serve le droit de supprimer, sans mise en demeure pr\u00e9alable, tout contenu d\u00e9pos\u00e9 dans cet espace qui contreviendrait \u00e0 la l\u00e9gislation applicable en France, en particulier aux dispositions relatives \u00e0 la protection des donn\u00e9es. Le cas \u00e9ch\u00e9ant, https:\/\/pagani-design.eu\/ se r\u00e9serve \u00e9galement la possibilit\u00e9 de mettre en cause la responsabilit\u00e9 civile et\/ou p\u00e9nale de l\u2019utilisateur, notamment en cas de message \u00e0 caract\u00e8re raciste, injurieux, diffamant, ou pornographique, quel que soit le support utilis\u00e9 (texte, photographie \u2026). 6. Gestion des donn\u00e9es personnelles. Le Client est inform\u00e9 des r\u00e9glementations concernant la communication marketing, la loi du 21 Juin 2014 pour la confiance dans l\u2019Economie Num\u00e9rique, la Loi Informatique et Libert\u00e9 du 06 Ao\u00fbt 2004 ainsi que du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679). 6.1 Responsables de la collecte des donn\u00e9es personnelles Pour les Donn\u00e9es Personnelles collect\u00e9es dans le cadre de la cr\u00e9ation du compte personnel de [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-7490","page","type-page","status-publish","hentry","post-no-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mentions l\u00e9gales - Pagani Design<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pagani-design.eu\/es\/informacion-legal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mentions l\u00e9gales - Pagani Design\" \/>\n<meta property=\"og:description\" content=\"D\u00e9finitions Client : tout professionnel ou personne physique capable au sens des articles 1123 et suivants du Code civil, ou personne morale, qui visite le Site objet des pr\u00e9sentes conditions g\u00e9n\u00e9rales.Prestations et Services : https:\/\/pagani-design.eu\/ met \u00e0 disposition des Clients : Contenu : Ensemble des \u00e9l\u00e9ments constituants l\u2019information pr\u00e9sente sur le Site, notamment textes \u2013 images \u2013 vid\u00e9os. Informations clients : Ci apr\u00e8s d\u00e9nomm\u00e9 \u00ab Information (s) \u00bb qui correspondent \u00e0 l\u2019ensemble des donn\u00e9es personnelles susceptibles d\u2019\u00eatre d\u00e9tenues par https:\/\/pagani-design.eu\/ pour la gestion de votre compte, de la gestion de la relation client et \u00e0 des fins d\u2019analyses et de statistiques. Utilisateur : Internaute se connectant, utilisant le site susnomm\u00e9. Informations personnelles : \u00ab Les informations qui permettent, sous quelque forme que ce soit, directement ou non, l&#8217;identification des personnes physiques auxquelles elles s&#8217;appliquent \u00bb (article 4 de la loi n\u00b0 78-17 du 6 janvier 1978). Les termes \u00ab donn\u00e9es \u00e0 caract\u00e8re personnel \u00bb, \u00ab personne concern\u00e9e \u00bb, \u00ab sous traitant \u00bb et \u00ab donn\u00e9es sensibles \u00bb ont le sens d\u00e9fini par le R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679) 1. Pr\u00e9sentation du site internet. En vertu de l&#8217;article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l&#8217;\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet https:\/\/pagani-design.eu\/ l&#8217;identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi: ALAMBIK\u00a0O2 switch \u2013 222-224 Boulevard Gustave Flaubert 63000 Clermont-Ferrand 09 3 645 729\u00a0bonjour@pagani-design.eu 2. Conditions g\u00e9n\u00e9rales d\u2019utilisation du site et des services propos\u00e9s. Le Site constitue une \u0153uvre de l\u2019esprit prot\u00e9g\u00e9e par les dispositions du Code de la Propri\u00e9t\u00e9 Intellectuelle et des R\u00e9glementations Internationales applicables. Le Client ne peut en aucune mani\u00e8re r\u00e9utiliser, c\u00e9der ou exploiter pour son propre compte tout ou partie des \u00e9l\u00e9ments ou travaux du Site. L\u2019utilisation du site https:\/\/pagani-design.eu\/ implique l\u2019acceptation pleine et enti\u00e8re des conditions g\u00e9n\u00e9rales d\u2019utilisation ci-apr\u00e8s d\u00e9crites. Ces conditions d\u2019utilisation sont susceptibles d\u2019\u00eatre modifi\u00e9es ou compl\u00e9t\u00e9es \u00e0 tout moment, les utilisateurs du site https:\/\/pagani-design.eu\/ sont donc invit\u00e9s \u00e0 les consulter de mani\u00e8re r\u00e9guli\u00e8re. Ce site internet est normalement accessible \u00e0 tout moment aux utilisateurs. Une interruption pour raison de maintenance technique peut \u00eatre toutefois d\u00e9cid\u00e9e par https:\/\/pagani-design.eu\/, qui s\u2019efforcera alors de communiquer pr\u00e9alablement aux utilisateurs les dates et heures de l\u2019intervention. Le site web https:\/\/pagani-design.eu\/ est mis \u00e0 jour r\u00e9guli\u00e8rement par https:\/\/pagani-design.eu\/ responsable. De la m\u00eame fa\u00e7on, les mentions l\u00e9gales peuvent \u00eatre modifi\u00e9es \u00e0 tout moment : elles s\u2019imposent n\u00e9anmoins \u00e0 l\u2019utilisateur qui est invit\u00e9 \u00e0 s\u2019y r\u00e9f\u00e9rer le plus souvent possible afin d\u2019en prendre connaissance. 3. Description des services fournis. Le site internet https:\/\/pagani-design.eu\/ a pour objet de fournir une information concernant l\u2019ensemble des activit\u00e9s de la soci\u00e9t\u00e9. https:\/\/pagani-design.eu\/ s\u2019efforce de fournir sur le site https:\/\/pagani-design.eu\/ des informations aussi pr\u00e9cises que possible. Toutefois, il ne pourra \u00eatre tenu responsable des oublis, des inexactitudes et des carences dans la mise \u00e0 jour, qu\u2019elles soient de son fait ou du fait des tiers partenaires qui lui fournissent ces informations. Toutes les informations indiqu\u00e9es sur le site https:\/\/pagani-design.eu\/ sont donn\u00e9es \u00e0 titre indicatif, et sont susceptibles d\u2019\u00e9voluer. Par ailleurs, les renseignements figurant sur le site https:\/\/pagani-design.eu\/ ne sont pas exhaustifs. Ils sont donn\u00e9s sous r\u00e9serve de modifications ayant \u00e9t\u00e9 apport\u00e9es depuis leur mise en ligne. 4. Limitations contractuelles sur les donn\u00e9es techniques. Le site utilise la technologie JavaScript. Le site Internet ne pourra \u00eatre tenu responsable de dommages mat\u00e9riels li\u00e9s \u00e0 l\u2019utilisation du site. De plus, l\u2019utilisateur du site s\u2019engage \u00e0 acc\u00e9der au site en utilisant un mat\u00e9riel r\u00e9cent, ne contenant pas de virus et avec un navigateur de derni\u00e8re g\u00e9n\u00e9ration mis-\u00e0-jour Le site https:\/\/pagani-design.eu\/ est h\u00e9berg\u00e9 chez un prestataire sur le territoire de l\u2019Union Europ\u00e9enne conform\u00e9ment aux dispositions du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679) L\u2019objectif est d\u2019apporter une prestation qui assure le meilleur taux d\u2019accessibilit\u00e9. L\u2019h\u00e9bergeur assure la continuit\u00e9 de son service 24 Heures sur 24, tous les jours de l\u2019ann\u00e9e. Il se r\u00e9serve n\u00e9anmoins la possibilit\u00e9 d\u2019interrompre le service d\u2019h\u00e9bergement pour les dur\u00e9es les plus courtes possibles notamment \u00e0 des fins de maintenance, d\u2019am\u00e9lioration de ses infrastructures, de d\u00e9faillance de ses infrastructures ou si les Prestations et Services g\u00e9n\u00e8rent un trafic r\u00e9put\u00e9 anormal. https:\/\/pagani-design.eu\/ et l\u2019h\u00e9bergeur ne pourront \u00eatre tenus responsables en cas de dysfonctionnement du r\u00e9seau Internet, des lignes t\u00e9l\u00e9phoniques ou du mat\u00e9riel informatique et de t\u00e9l\u00e9phonie li\u00e9 notamment \u00e0 l\u2019encombrement du r\u00e9seau emp\u00eachant l\u2019acc\u00e8s au serveur. 5. Limitations de responsabilit\u00e9. https:\/\/pagani-design.eu\/ agit en tant qu\u2019\u00e9diteur du site. https:\/\/pagani-design.eu\/ est responsable de la qualit\u00e9 et de la v\u00e9racit\u00e9 du Contenu qu\u2019il publie. https:\/\/pagani-design.eu\/ ne pourra \u00eatre tenu responsable des dommages directs et indirects caus\u00e9s au mat\u00e9riel de l\u2019utilisateur, lors de l\u2019acc\u00e8s au site internet https:\/\/pagani-design.eu\/, et r\u00e9sultant soit de l\u2019utilisation d\u2019un mat\u00e9riel ne r\u00e9pondant pas aux sp\u00e9cifications indiqu\u00e9es au point 4, soit de l\u2019apparition d\u2019un bug ou d\u2019une incompatibilit\u00e9. https:\/\/pagani-design.eu\/ ne pourra \u00e9galement \u00eatre tenu responsable des dommages indirects (tels par exemple qu\u2019une perte de march\u00e9 ou perte d\u2019une chance) cons\u00e9cutifs \u00e0 l\u2019utilisation du site https:\/\/pagani-design.eu\/. Des espaces interactifs (possibilit\u00e9 de poser des questions dans l\u2019espace contact) sont \u00e0 la disposition des utilisateurs. https:\/\/pagani-design.eu\/ se r\u00e9serve le droit de supprimer, sans mise en demeure pr\u00e9alable, tout contenu d\u00e9pos\u00e9 dans cet espace qui contreviendrait \u00e0 la l\u00e9gislation applicable en France, en particulier aux dispositions relatives \u00e0 la protection des donn\u00e9es. Le cas \u00e9ch\u00e9ant, https:\/\/pagani-design.eu\/ se r\u00e9serve \u00e9galement la possibilit\u00e9 de mettre en cause la responsabilit\u00e9 civile et\/ou p\u00e9nale de l\u2019utilisateur, notamment en cas de message \u00e0 caract\u00e8re raciste, injurieux, diffamant, ou pornographique, quel que soit le support utilis\u00e9 (texte, photographie \u2026). 6. Gestion des donn\u00e9es personnelles. Le Client est inform\u00e9 des r\u00e9glementations concernant la communication marketing, la loi du 21 Juin 2014 pour la confiance dans l\u2019Economie Num\u00e9rique, la Loi Informatique et Libert\u00e9 du 06 Ao\u00fbt 2004 ainsi que du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679). 6.1 Responsables de la collecte des donn\u00e9es personnelles Pour les Donn\u00e9es Personnelles collect\u00e9es dans le cadre de la cr\u00e9ation du compte personnel de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pagani-design.eu\/es\/informacion-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Pagani Design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61561029376509\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-20T12:20:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pagani-design.eu\/wp-content\/uploads\/2022\/01\/Montre-robuste-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pagani-design.eu\/mentions-legales\/\",\"url\":\"https:\/\/pagani-design.eu\/mentions-legales\/\",\"name\":\"Mentions l\u00e9gales - Pagani Design\",\"isPartOf\":{\"@id\":\"https:\/\/pagani-design.eu\/de\/#website\"},\"datePublished\":\"2023-06-23T12:32:07+00:00\",\"dateModified\":\"2024-09-20T12:20:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pagani-design.eu\/mentions-legales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pagani-design.eu\/mentions-legales\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pagani-design.eu\/mentions-legales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/pagani-design.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mentions l\u00e9gales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pagani-design.eu\/de\/#website\",\"url\":\"https:\/\/pagani-design.eu\/de\/\",\"name\":\"Pagani Design\",\"description\":\"Pagani Design\",\"publisher\":{\"@id\":\"https:\/\/pagani-design.eu\/de\/#organization\"},\"alternateName\":\"Pagani Design\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pagani-design.eu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pagani-design.eu\/de\/#organization\",\"name\":\"Pagani Design\",\"alternateName\":\"Pagani Design\",\"url\":\"https:\/\/pagani-design.eu\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pagani-design.eu\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pagani-design.eu\/wp-content\/uploads\/2022\/01\/Montre-robuste-1.png\",\"contentUrl\":\"https:\/\/pagani-design.eu\/wp-content\/uploads\/2022\/01\/Montre-robuste-1.png\",\"width\":750,\"height\":259,\"caption\":\"Pagani Design\"},\"image\":{\"@id\":\"https:\/\/pagani-design.eu\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=61561029376509\",\"https:\/\/www.instagram.com\/pagani_design.fr\",\"https:\/\/www.tiktok.com\/@pagani_design.fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Menciones legales - Pagani Design","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pagani-design.eu\/es\/informacion-legal\/","og_locale":"es_ES","og_type":"article","og_title":"Mentions l\u00e9gales - Pagani Design","og_description":"D\u00e9finitions Client : tout professionnel ou personne physique capable au sens des articles 1123 et suivants du Code civil, ou personne morale, qui visite le Site objet des pr\u00e9sentes conditions g\u00e9n\u00e9rales.Prestations et Services : https:\/\/pagani-design.eu\/ met \u00e0 disposition des Clients : Contenu : Ensemble des \u00e9l\u00e9ments constituants l\u2019information pr\u00e9sente sur le Site, notamment textes \u2013 images \u2013 vid\u00e9os. Informations clients : Ci apr\u00e8s d\u00e9nomm\u00e9 \u00ab Information (s) \u00bb qui correspondent \u00e0 l\u2019ensemble des donn\u00e9es personnelles susceptibles d\u2019\u00eatre d\u00e9tenues par https:\/\/pagani-design.eu\/ pour la gestion de votre compte, de la gestion de la relation client et \u00e0 des fins d\u2019analyses et de statistiques. Utilisateur : Internaute se connectant, utilisant le site susnomm\u00e9. Informations personnelles : \u00ab Les informations qui permettent, sous quelque forme que ce soit, directement ou non, l&#8217;identification des personnes physiques auxquelles elles s&#8217;appliquent \u00bb (article 4 de la loi n\u00b0 78-17 du 6 janvier 1978). Les termes \u00ab donn\u00e9es \u00e0 caract\u00e8re personnel \u00bb, \u00ab personne concern\u00e9e \u00bb, \u00ab sous traitant \u00bb et \u00ab donn\u00e9es sensibles \u00bb ont le sens d\u00e9fini par le R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679) 1. Pr\u00e9sentation du site internet. En vertu de l&#8217;article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l&#8217;\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet https:\/\/pagani-design.eu\/ l&#8217;identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi: ALAMBIK\u00a0O2 switch \u2013 222-224 Boulevard Gustave Flaubert 63000 Clermont-Ferrand 09 3 645 729\u00a0bonjour@pagani-design.eu 2. Conditions g\u00e9n\u00e9rales d\u2019utilisation du site et des services propos\u00e9s. Le Site constitue une \u0153uvre de l\u2019esprit prot\u00e9g\u00e9e par les dispositions du Code de la Propri\u00e9t\u00e9 Intellectuelle et des R\u00e9glementations Internationales applicables. Le Client ne peut en aucune mani\u00e8re r\u00e9utiliser, c\u00e9der ou exploiter pour son propre compte tout ou partie des \u00e9l\u00e9ments ou travaux du Site. L\u2019utilisation du site https:\/\/pagani-design.eu\/ implique l\u2019acceptation pleine et enti\u00e8re des conditions g\u00e9n\u00e9rales d\u2019utilisation ci-apr\u00e8s d\u00e9crites. Ces conditions d\u2019utilisation sont susceptibles d\u2019\u00eatre modifi\u00e9es ou compl\u00e9t\u00e9es \u00e0 tout moment, les utilisateurs du site https:\/\/pagani-design.eu\/ sont donc invit\u00e9s \u00e0 les consulter de mani\u00e8re r\u00e9guli\u00e8re. Ce site internet est normalement accessible \u00e0 tout moment aux utilisateurs. Une interruption pour raison de maintenance technique peut \u00eatre toutefois d\u00e9cid\u00e9e par https:\/\/pagani-design.eu\/, qui s\u2019efforcera alors de communiquer pr\u00e9alablement aux utilisateurs les dates et heures de l\u2019intervention. Le site web https:\/\/pagani-design.eu\/ est mis \u00e0 jour r\u00e9guli\u00e8rement par https:\/\/pagani-design.eu\/ responsable. De la m\u00eame fa\u00e7on, les mentions l\u00e9gales peuvent \u00eatre modifi\u00e9es \u00e0 tout moment : elles s\u2019imposent n\u00e9anmoins \u00e0 l\u2019utilisateur qui est invit\u00e9 \u00e0 s\u2019y r\u00e9f\u00e9rer le plus souvent possible afin d\u2019en prendre connaissance. 3. Description des services fournis. Le site internet https:\/\/pagani-design.eu\/ a pour objet de fournir une information concernant l\u2019ensemble des activit\u00e9s de la soci\u00e9t\u00e9. https:\/\/pagani-design.eu\/ s\u2019efforce de fournir sur le site https:\/\/pagani-design.eu\/ des informations aussi pr\u00e9cises que possible. Toutefois, il ne pourra \u00eatre tenu responsable des oublis, des inexactitudes et des carences dans la mise \u00e0 jour, qu\u2019elles soient de son fait ou du fait des tiers partenaires qui lui fournissent ces informations. Toutes les informations indiqu\u00e9es sur le site https:\/\/pagani-design.eu\/ sont donn\u00e9es \u00e0 titre indicatif, et sont susceptibles d\u2019\u00e9voluer. Par ailleurs, les renseignements figurant sur le site https:\/\/pagani-design.eu\/ ne sont pas exhaustifs. Ils sont donn\u00e9s sous r\u00e9serve de modifications ayant \u00e9t\u00e9 apport\u00e9es depuis leur mise en ligne. 4. Limitations contractuelles sur les donn\u00e9es techniques. Le site utilise la technologie JavaScript. Le site Internet ne pourra \u00eatre tenu responsable de dommages mat\u00e9riels li\u00e9s \u00e0 l\u2019utilisation du site. De plus, l\u2019utilisateur du site s\u2019engage \u00e0 acc\u00e9der au site en utilisant un mat\u00e9riel r\u00e9cent, ne contenant pas de virus et avec un navigateur de derni\u00e8re g\u00e9n\u00e9ration mis-\u00e0-jour Le site https:\/\/pagani-design.eu\/ est h\u00e9berg\u00e9 chez un prestataire sur le territoire de l\u2019Union Europ\u00e9enne conform\u00e9ment aux dispositions du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679) L\u2019objectif est d\u2019apporter une prestation qui assure le meilleur taux d\u2019accessibilit\u00e9. L\u2019h\u00e9bergeur assure la continuit\u00e9 de son service 24 Heures sur 24, tous les jours de l\u2019ann\u00e9e. Il se r\u00e9serve n\u00e9anmoins la possibilit\u00e9 d\u2019interrompre le service d\u2019h\u00e9bergement pour les dur\u00e9es les plus courtes possibles notamment \u00e0 des fins de maintenance, d\u2019am\u00e9lioration de ses infrastructures, de d\u00e9faillance de ses infrastructures ou si les Prestations et Services g\u00e9n\u00e8rent un trafic r\u00e9put\u00e9 anormal. https:\/\/pagani-design.eu\/ et l\u2019h\u00e9bergeur ne pourront \u00eatre tenus responsables en cas de dysfonctionnement du r\u00e9seau Internet, des lignes t\u00e9l\u00e9phoniques ou du mat\u00e9riel informatique et de t\u00e9l\u00e9phonie li\u00e9 notamment \u00e0 l\u2019encombrement du r\u00e9seau emp\u00eachant l\u2019acc\u00e8s au serveur. 5. Limitations de responsabilit\u00e9. https:\/\/pagani-design.eu\/ agit en tant qu\u2019\u00e9diteur du site. https:\/\/pagani-design.eu\/ est responsable de la qualit\u00e9 et de la v\u00e9racit\u00e9 du Contenu qu\u2019il publie. https:\/\/pagani-design.eu\/ ne pourra \u00eatre tenu responsable des dommages directs et indirects caus\u00e9s au mat\u00e9riel de l\u2019utilisateur, lors de l\u2019acc\u00e8s au site internet https:\/\/pagani-design.eu\/, et r\u00e9sultant soit de l\u2019utilisation d\u2019un mat\u00e9riel ne r\u00e9pondant pas aux sp\u00e9cifications indiqu\u00e9es au point 4, soit de l\u2019apparition d\u2019un bug ou d\u2019une incompatibilit\u00e9. https:\/\/pagani-design.eu\/ ne pourra \u00e9galement \u00eatre tenu responsable des dommages indirects (tels par exemple qu\u2019une perte de march\u00e9 ou perte d\u2019une chance) cons\u00e9cutifs \u00e0 l\u2019utilisation du site https:\/\/pagani-design.eu\/. Des espaces interactifs (possibilit\u00e9 de poser des questions dans l\u2019espace contact) sont \u00e0 la disposition des utilisateurs. https:\/\/pagani-design.eu\/ se r\u00e9serve le droit de supprimer, sans mise en demeure pr\u00e9alable, tout contenu d\u00e9pos\u00e9 dans cet espace qui contreviendrait \u00e0 la l\u00e9gislation applicable en France, en particulier aux dispositions relatives \u00e0 la protection des donn\u00e9es. Le cas \u00e9ch\u00e9ant, https:\/\/pagani-design.eu\/ se r\u00e9serve \u00e9galement la possibilit\u00e9 de mettre en cause la responsabilit\u00e9 civile et\/ou p\u00e9nale de l\u2019utilisateur, notamment en cas de message \u00e0 caract\u00e8re raciste, injurieux, diffamant, ou pornographique, quel que soit le support utilis\u00e9 (texte, photographie \u2026). 6. Gestion des donn\u00e9es personnelles. Le Client est inform\u00e9 des r\u00e9glementations concernant la communication marketing, la loi du 21 Juin 2014 pour la confiance dans l\u2019Economie Num\u00e9rique, la Loi Informatique et Libert\u00e9 du 06 Ao\u00fbt 2004 ainsi que du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679). 6.1 Responsables de la collecte des donn\u00e9es personnelles Pour les Donn\u00e9es Personnelles collect\u00e9es dans le cadre de la cr\u00e9ation du compte personnel de [&hellip;]","og_url":"https:\/\/pagani-design.eu\/es\/informacion-legal\/","og_site_name":"Pagani Design","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61561029376509","article_modified_time":"2024-09-20T12:20:47+00:00","og_image":[{"width":750,"height":259,"url":"https:\/\/pagani-design.eu\/wp-content\/uploads\/2022\/01\/Montre-robuste-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pagani-design.eu\/mentions-legales\/","url":"https:\/\/pagani-design.eu\/mentions-legales\/","name":"Menciones legales - Pagani Design","isPartOf":{"@id":"https:\/\/pagani-design.eu\/de\/#website"},"datePublished":"2023-06-23T12:32:07+00:00","dateModified":"2024-09-20T12:20:47+00:00","breadcrumb":{"@id":"https:\/\/pagani-design.eu\/mentions-legales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pagani-design.eu\/mentions-legales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pagani-design.eu\/mentions-legales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/pagani-design.eu\/"},{"@type":"ListItem","position":2,"name":"Mentions l\u00e9gales"}]},{"@type":"WebSite","@id":"https:\/\/pagani-design.eu\/de\/#website","url":"https:\/\/pagani-design.eu\/de\/","name":"Pagani Design","description":"Pagani Design","publisher":{"@id":"https:\/\/pagani-design.eu\/de\/#organization"},"alternateName":"Pagani Design","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pagani-design.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pagani-design.eu\/de\/#organization","name":"Pagani Design","alternateName":"Pagani Design","url":"https:\/\/pagani-design.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pagani-design.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/pagani-design.eu\/wp-content\/uploads\/2022\/01\/Montre-robuste-1.png","contentUrl":"https:\/\/pagani-design.eu\/wp-content\/uploads\/2022\/01\/Montre-robuste-1.png","width":750,"height":259,"caption":"Pagani Design"},"image":{"@id":"https:\/\/pagani-design.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61561029376509","https:\/\/www.instagram.com\/pagani_design.fr","https:\/\/www.tiktok.com\/@pagani_design.fr"]}]}},"_links":{"self":[{"href":"https:\/\/pagani-design.eu\/es\/wp-json\/wp\/v2\/pages\/7490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pagani-design.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pagani-design.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pagani-design.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pagani-design.eu\/es\/wp-json\/wp\/v2\/comments?post=7490"}],"version-history":[{"count":0,"href":"https:\/\/pagani-design.eu\/es\/wp-json\/wp\/v2\/pages\/7490\/revisions"}],"wp:attachment":[{"href":"https:\/\/pagani-design.eu\/es\/wp-json\/wp\/v2\/media?parent=7490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}